{"id":16315,"date":"2024-10-25T18:48:15","date_gmt":"2024-10-25T18:48:15","guid":{"rendered":"https:\/\/seonetdigital.com\/?p=16315"},"modified":"2025-01-18T15:24:00","modified_gmt":"2025-01-18T15:24:00","slug":"h1-h2-h3","status":"publish","type":"post","link":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3","title":{"rendered":"Etiquetas de encabezados: h1, h2, h3 \u00bfQu\u00e9 son y c\u00f3mo se usan?"},"content":{"rendered":"<p>En el entorno digital, la forma de organizar el contenido de una p\u00e1gina web es con el uso de etiquetas HTML. En el caso de los encabezados se usan<b> las <\/b><b><i>tags <\/i><\/b><b>h1, h2, h3<\/b>, incluso hasta h6.<\/p>\n<p>Los encabezados ayudan a los usuarios a leer el texto y a los motores de b\u00fasqueda a entender cu\u00e1l es el tema principal de una p\u00e1gina web. \u00bfLo sab\u00edas?<\/p>\n<h2>\u00bfQu\u00e9 son las etiquetas de encabezados?<\/h2>\n<p>Las etiquetas de encabezado HTML se usan para <b>marcar los t\u00edtulos (<\/b><b><i>headings<\/i><\/b><b>) y subt\u00edtulos del contenido<\/b> de una p\u00e1gina web. Aunque no existe un n\u00famero fijo, lo m\u00e1s com\u00fan es que los encontremos desde el h1 al h6.<\/p>\n<p>Aunque su forma de uso es simple, estas etiquetas suelen ser mal utilizadas y no se les asigna la funci\u00f3n que realmente tienen. Esto es un gran error, dado que la estructura de encabezados influye de forma directa en dos factores que hacen al \u00e9xito de tu sitio web: <b>el SEO y la <\/b><a href=\"https:\/\/seonetdigital.com\/es\/blog\/que-es-experiencia-de-usuario\"><b>experiencia de usuario<\/b><\/a>.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/seonetdigital.com\/wp-content\/uploads\/2025\/01\/use-encabezados-html-solo-para-titulos-1400x619.jpg\" alt=\"use encabezados html solo para titulos\" width=\"1020\" height=\"451\" \/><\/p>\n<h2>\u00bfQu\u00e9 es h1?<\/h2>\n<p>La etiqueta o tag h1 es la que se asigna al <b>t\u00edtulo principal de una p\u00e1gina<\/b>. No hay que confundirla con la etiqueta Meta Title que indica el t\u00edtulo del sitio web y es el que aparece en las SERPS y en la pesta\u00f1a del navegador. Esta \u00faltima se encuentra m\u00e1s orientada al SEO, mientras <b>el h1 es m\u00e1s importante para el usuario<\/b>.<\/p>\n<p>Otras caracter\u00edsticas del h1 son:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Debe aparecer lo m\u00e1s arriba posible de la p\u00e1gina que es donde las personas comienzan a leer.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>Cada p\u00e1gina debe tener s\u00f3lo un h1<\/b>.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">No tiene que tener enlaces hacia otro contenido.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Contiene la palabra clave principal, lo m\u00e1s a la izquierda posible. Si es al principio, mejor.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Tiene que ser corto y <b>dejar claro cu\u00e1l es el tema del contenido<\/b>.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">No lleva puntos, debe tener informaci\u00f3n completa, en una sola idea.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Debe estar optimizado para SEO.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Puede aparecer en las SERPS, si Google lo considera m\u00e1s valioso y representativo que el metatitle.<\/li>\n<\/ul>\n<p><img decoding=\"async\" src=\"https:\/\/seonetdigital.com\/wp-content\/uploads\/2025\/01\/que-es-h1-y-h2-1536x1287.jpg\" alt=\"que es h1 y h2\" width=\"1020\" height=\"855\" \/><\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/Nckhfz1PrrA?si=gMCbI-T46QNtPVIt\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<h2>\u00bfQu\u00e9 es h2?<\/h2>\n<p>La <b>etiqueta o tag h2 se utiliza para marcar los subt\u00edtulos<\/b> de una publicaci\u00f3n en una p\u00e1gina web. Si haces una analog\u00eda con un libro, los h2 ser\u00edan los cap\u00edtulos.<\/p>\n<p>Los h2 se caracterizan por:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Estar subordinados al h1.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">No tener una cantidad m\u00ednima ni m\u00e1xima, puede haber varios h2 por p\u00e1gina.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Describir en pocas palabras el contenido que est\u00e1 en los p\u00e1rrafos a continuaci\u00f3n.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Incluir en su redacci\u00f3n palabras clave sem\u00e1nticas que completen el sentido del texto.<\/li>\n<\/ul>\n<blockquote><p>\u00abRecuerde, Google escanear\u00e1 el HTML de las etiquetas de encabezado para decirle a los navegadores web de qu\u00e9 trata su p\u00e1gina, por lo que es importante revisarlas y ver si sus encabezados en HTML est\u00e1n formateados correctamente.\u00bb Fuente: <a href=\"https:\/\/blog.hubspot.com\/marketing\/header-tags\">Hubspot<\/a><\/p><\/blockquote>\n<h2>\u00bfQu\u00e9 es h3, h4 y m\u00e1s?<\/h2>\n<p>Las <b>etiquetas o tag h3 se organizan por debajo del h2<\/b>, indicando subtemas. Es importante prestar atenci\u00f3n a la jerarqu\u00eda de t\u00edtulos: Primero el h1, luego las secciones con h2 y dentro de \u00e9stas las subsecciones con h3. No puede haber h3, si no existe un h2 que lo contenga.<\/p>\n<p>El mismo orden l\u00f3gico se debe seguir a medida que agregamos contenido subordinado al h3, que lo indicamos como h4, y as\u00ed sucesivamente.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/seonetdigital.com\/wp-content\/uploads\/2025\/01\/codigo-ejemplo-de-h1-h2-y-h3-1149x800.jpg\" alt=\"codigo ejemplo de h1 h2 y h3\" width=\"1020\" height=\"710\" \/><\/p>\n<h2>\u00bfPor qu\u00e9 son importantes las etiquetas &lt;h&gt;?<\/h2>\n<p>Los h1, h2, h3 y m\u00e1s, te ofrecen un panorama completo del contenido de la p\u00e1gina. Incluso si eliminas todos los p\u00e1rrafos y dejas solo los headings, sabr\u00e1s de qu\u00e9 trata el contenido.<\/p>\n<p>Pero adem\u00e1s de esta cualidad, <b>son importantes por las siguientes razones:<\/b><\/p>\n<h3>Mejoran la accesibilidad<\/h3>\n<p>Los encabezados h1, h2, h3, etc, indicados en HTML, son accesibles para los lectores de pantalla, por lo tanto, facilitan la navegabilidad de los sitios para personas con discapacidad visual. \u00a1<b>Mejor accesibilidad y navegabilidad <\/b>son importantes para el posicionamiento SEO!<\/p>\n<blockquote><p>\u00ab\u200cLos encabezados comunican la organizaci\u00f3n del contenido en la p\u00e1gina. Los navegadores web, complementos y tecnolog\u00edas de asistencia pueden usarlos para proporcionar navegaci\u00f3n en la p\u00e1gina.\u00bb Fuente: <a href=\"https:\/\/www.w3.org\/WAI\/tutorials\/page-structure\/headings\/\">Web Accessibility Initiative (WAI).<\/a><\/p><\/blockquote>\n<h3>Influyen positivamente en el SEO<\/h3>\n<p>Aunque los encabezados por s\u00ed solos no son un factor de posicionamiento determinante, su uso correcto aporta para tener textos de m\u00e1s calidad y para que las personas encuentren m\u00e1s f\u00e1cilmente lo que buscan. Ambos aspectos s\u00ed <b>pueden influir de manera significativa en el SEO de tu sitio.<\/b><\/p>\n<h2>Buenas pr\u00e1cticas para escribir tus encabezados<\/h2>\n<p>Las etiquetas de encabezado HTML se agregan en el c\u00f3digo o aparecen en los gestores de contenido de forma ordenada y con un tama\u00f1o decreciente de &lt;h1&gt; a &lt;h6&gt;, aunque en general se utiliza hasta el &lt;h4&gt;.<\/p>\n<p>Para <b>escribirlos y estructurarlos de manera correcta,<\/b> sigue estas pr\u00e1cticas:<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Usar <b>t\u00edtulos descriptivos<\/b> para ayudar al usuario a navegar por tu p\u00e1gina.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Independientemente de la jerarqu\u00eda, procurar siempre redactar t\u00edtulos \u00fanicos.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Escribir t\u00edtulos que presenten el prop\u00f3sito principal del contenido.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><b>No colocar enlaces<\/b> en los t\u00edtulos. Seg\u00fan <a href=\"https:\/\/developers.google.com\/style\/headings\">Google<\/a>, <i>\u00abpuede confundirse f\u00e1cilmente como un estilo aplicado a un encabezado en lugar de un enlace.\u00bb<\/i><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Evitar el uso del gerundio para t\u00edtulos ya que <b>aumentan el recuento de caracteres<\/b>. Por ejemplo, prefiere \u00abCrear\u00bb, en vez de \u00abCreando\u00bb para contenidos sobre tareas, o \u00abMigraci\u00f3n\u00bb, en vez de \u00abMigrando\u00bb para contenidos conceptuales.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Si es posible, no repetir el t\u00edtulo SEO (tag Title) en un encabezado de la p\u00e1gina.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Respetar los<b> niveles de la jerarqu\u00eda de encabezado<\/b>. Por ejemplo, un &lt;h3&gt; solo se coloca debajo de un &lt;h2&gt;.<\/li>\n<\/ul>\n<p><b>Ejemplo correcto (h2 luego del h1):<\/b><\/p>\n<p>&lt;h1&gt; \u00bfC\u00f3mo viajar barato a Mar del Plata? &lt;\/h1&gt;<\/p>\n<p>&lt;p&gt; p\u00e1rrafo<\/p>\n<p>&lt;h2&gt; Costos estimados para viajar a Mar del Plata &lt;\/h2&gt;<\/p>\n<p><b>Ejemplo incorrecto (h3 luego del h1, sin pasar por el h2)<\/b>:<\/p>\n<p>&lt;h1&gt; \u00bfC\u00f3mo viajar barato a Mar del Plata? &lt;\/h1&gt;<\/p>\n<p>&lt;p&gt; p\u00e1rrafo<\/p>\n<p>&lt;h3&gt; Costos estimados para viajar a Mar del Plata &lt;\/h3&gt;<\/p>\n<h2>Ejemplo de una estructura h1, h2, h3 completa<\/h2>\n<p>En una publicaci\u00f3n de blog sobre \u00abzapatillas de running\u00bb, esta podr\u00eda ser la <b>estructura de encabezados<\/b>:<\/p>\n<p><strong>H1<\/strong>: Zapatillas de running: \u00bfc\u00f3mo elegir las mejores para ti?<\/p>\n<ul>\n<li>H2: \u00bfQu\u00e9 tener en cuenta al elegir las zapatillas de running?\n<ul>\n<li>H3: Tipo de pisada<\/li>\n<li>H3: Terreno donde corres<\/li>\n<li>H3: Comodidad y ajuste<\/li>\n<li>H3: Amortiguaci\u00f3n y soporte<\/li>\n<li>H3: Durabilidad y calidad<\/li>\n<li>H3: Materiales y tecnolog\u00eda de las zapatillas<\/li>\n<li>H3: Estilo y preferencias personales<\/li>\n<li>H3: Presupuesto y marca<\/li>\n<\/ul>\n<\/li>\n<li>H2: \u00bfD\u00f3nde deber\u00edas comprar tus zapatillas de running?\n<ul>\n<li>H3: Los diez mejores sitios web de venta de zapatillas<\/li>\n<li>H3: Nuestras tiendas locales favoritas<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Este es un excelente ejemplo de c\u00f3mo los encabezados deben estructurarse en un <b>art\u00edculo de longitud media<\/b>, con los h2 encabezando secciones y los h3 como subsecciones. Si deseas entrar en m\u00e1s detalles, tambi\u00e9n puedes usar etiquetas H4 y crear secciones de nivel inferior a los h3, <b>siempre respetando las jerarqu\u00edas<\/b>.<\/p>\n<p>Para resumir, te dejamos este video. Activa los subt\u00edtulos en espa\u00f1ol:<\/p>\n<p><iframe title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/GpExwKq0dXo?si=uT-hcXjecTtJNUlf\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<details id=\"e-n-accordion-item-1200\" style=\"padding-top: 20px;\">\n<summary tabindex=\"0\" data-accordion-index=\"1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1200\">\u00a0<a style=\"cursor: pointer;\">Fuentes de informaci\u00f3n consultadas:<\/a><\/summary>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\u200cGoogle for Developers (2024). <a href=\"https:\/\/developers.google.com\/style\/headings\"><i>Headings and titles<\/i><\/a>. Google.com<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\u200cCarmicheal, K. (2021). <a href=\"https:\/\/blog.hubspot.com\/marketing\/header-tags\"><i>Header Tags: What They Are and How to Use Them<\/i><\/a>. Hubspot.com.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Cunningham, C. (2021). <a href=\"https:\/\/yoast.com\/accessibility-matters\/\"><i>How to improve the accessibility of your website<\/i><\/a>. Yoast.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Garc\u00eda-Amaya, D. (2023). <a href=\"https:\/\/www.youtube.com\/watch?v=Nckhfz1PrrA\"><i>Todo sobre la etiqueta H1 en SEO | \u00bfQu\u00e9 es y para Qu\u00e9 se utiliza?<\/i><\/a> .YouTube Video<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">MDN Web Docs (2014) <a href=\"https:\/\/developer.mozilla.org\/es\/docs\/Web\/HTML\/Element\/Heading_Elements\"><i>Elementos t\u00edtulos \u2013 HTML: Lenguaje de etiquetas de hipertexto | MDN<\/i><\/a>. MDN Web Docs. \u200c<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\u200cUNAM (2020). <a href=\"https:\/\/www.visibilidadweb.unam.mx\/guia\/encabezados-h\"><i>Gu\u00eda T\u00e9cnica \u2013 Encabezados h | Visibilidad Web UNAM<\/i>. <\/a>Unam.mx.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">van de Rakt, M. (2018). <a href=\"https:\/\/yoast.com\/whats-the-difference-between-an-h1-heading-and-the-seo-title\/\"><i>What\u2019s the difference between an H1 heading and the SEO title?<\/i><\/a> Yoast.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">WAI. (2017). <a href=\"https:\/\/www.w3.org\/WAI\/tutorials\/page-structure\/headings\/\"><i>Headings<\/i><\/a>. Web Accessibility Initiative (WAI).<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">W3Schools.com. (2024). <a href=\"https:\/\/www.w3schools.com\/htmL\/html_headings.asp\"><i>Headings<\/i><\/a>. W3schools.com.<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">\u200cXara. (2023). <a href=\"https:\/\/www.youtube.com\/watch?v=GpExwKq0dXo\"><i>SEO: Structure Your Page\u2019s Content &amp; Headings | Xara<\/i><\/a> [YouTube Video]. In <i>YouTube<\/i>.<\/li>\n<\/ul>\n<\/details>\n","protected":false},"excerpt":{"rendered":"<p>En el entorno digital, la forma de organizar el contenido de una p\u00e1gina web es con el uso de etiquetas HTML. En el caso de los encabezados se usan las tags h1, h2, h3, incluso hasta h6. Los encabezados ayudan a los usuarios a leer el texto y a los motores de b\u00fasqueda a entender [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":22921,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[21],"tags":[],"class_list":["post-16315","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet<\/title>\n<meta name=\"description\" content=\"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet\" \/>\n<meta property=\"og:description\" content=\"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3\" \/>\n<meta property=\"og:site_name\" content=\"Digital Marketing Agency\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-25T18:48:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-18T15:24:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Ing. Pablo M. Suarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ing. Pablo M. Suarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3\"},\"author\":{\"name\":\"Ing. Pablo M. Suarez\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#\\\/schema\\\/person\\\/a0cc8abd08260fe41e36a9535aaaaa48\"},\"headline\":\"Etiquetas de encabezados: h1, h2, h3 \u00bfQu\u00e9 son y c\u00f3mo se usan?\",\"datePublished\":\"2024-10-25T18:48:15+00:00\",\"dateModified\":\"2025-01-18T15:24:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3\"},\"wordCount\":1378,\"publisher\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/h1-h2-y-h3-700x400-1.webp\",\"articleSection\":[\"Marketing digital\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3\",\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3\",\"name\":\"\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/h1-h2-y-h3-700x400-1.webp\",\"datePublished\":\"2024-10-25T18:48:15+00:00\",\"dateModified\":\"2025-01-18T15:24:00+00:00\",\"description\":\"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#primaryimage\",\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/h1-h2-y-h3-700x400-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/h1-h2-y-h3-700x400-1.webp\",\"width\":700,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/h1-h2-h3#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.seonetdigital.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Etiquetas de encabezados: h1, h2, h3 \u00bfQu\u00e9 son y c\u00f3mo se usan?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/\",\"name\":\"Digital Marketing Agency\",\"description\":\"Seonet Digital\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#organization\",\"name\":\"Digital Marketing Agency\",\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-logo-seonet.png\",\"contentUrl\":\"https:\\\/\\\/www.seonetdigital.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/cropped-logo-seonet.png\",\"width\":400,\"height\":74,\"caption\":\"Digital Marketing Agency\"},\"image\":{\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/#\\\/schema\\\/person\\\/a0cc8abd08260fe41e36a9535aaaaa48\",\"name\":\"Ing. Pablo M. Suarez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g\",\"caption\":\"Ing. Pablo M. Suarez\"},\"url\":\"https:\\\/\\\/www.seonetdigital.com\\\/es\\\/blog\\\/author\\\/pablo-suarez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet","description":"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet","og_description":"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!","og_url":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3","og_site_name":"Digital Marketing Agency","article_published_time":"2024-10-25T18:48:15+00:00","article_modified_time":"2025-01-18T15:24:00+00:00","og_image":[{"width":700,"height":400,"url":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp","type":"image\/webp"}],"author":"Ing. Pablo M. Suarez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Ing. Pablo M. Suarez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#article","isPartOf":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3"},"author":{"name":"Ing. Pablo M. Suarez","@id":"https:\/\/www.seonetdigital.com\/es\/#\/schema\/person\/a0cc8abd08260fe41e36a9535aaaaa48"},"headline":"Etiquetas de encabezados: h1, h2, h3 \u00bfQu\u00e9 son y c\u00f3mo se usan?","datePublished":"2024-10-25T18:48:15+00:00","dateModified":"2025-01-18T15:24:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3"},"wordCount":1378,"publisher":{"@id":"https:\/\/www.seonetdigital.com\/es\/#organization"},"image":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#primaryimage"},"thumbnailUrl":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp","articleSection":["Marketing digital"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3","url":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3","name":"\u00bfQue Son las Etiquetas de Encabezados? \u2013 Seonet","isPartOf":{"@id":"https:\/\/www.seonetdigital.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#primaryimage"},"image":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#primaryimage"},"thumbnailUrl":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp","datePublished":"2024-10-25T18:48:15+00:00","dateModified":"2025-01-18T15:24:00+00:00","description":"Saber c\u00f3mo utilizar las etiquetas de encabezados h1, h2, h3 es fundamental para el \u00e9xito de tu sitio web. \u00a1Ent\u00e9rate c\u00f3mo hacerlo de manera correcta!","breadcrumb":{"@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#primaryimage","url":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp","contentUrl":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/10\/h1-h2-y-h3-700x400-1.webp","width":700,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.seonetdigital.com\/es\/blog\/h1-h2-h3#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.seonetdigital.com\/"},{"@type":"ListItem","position":2,"name":"Etiquetas de encabezados: h1, h2, h3 \u00bfQu\u00e9 son y c\u00f3mo se usan?"}]},{"@type":"WebSite","@id":"https:\/\/www.seonetdigital.com\/es\/#website","url":"https:\/\/www.seonetdigital.com\/es\/","name":"Digital Marketing Agency","description":"Seonet Digital","publisher":{"@id":"https:\/\/www.seonetdigital.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.seonetdigital.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.seonetdigital.com\/es\/#organization","name":"Digital Marketing Agency","url":"https:\/\/www.seonetdigital.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.seonetdigital.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/09\/cropped-logo-seonet.png","contentUrl":"https:\/\/www.seonetdigital.com\/wp-content\/uploads\/2024\/09\/cropped-logo-seonet.png","width":400,"height":74,"caption":"Digital Marketing Agency"},"image":{"@id":"https:\/\/www.seonetdigital.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.seonetdigital.com\/es\/#\/schema\/person\/a0cc8abd08260fe41e36a9535aaaaa48","name":"Ing. Pablo M. Suarez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d3e82b0d88d1a793d1a7be8125098cf5fd19756014abc16e6a808ce9bf918e5?s=96&d=mm&r=g","caption":"Ing. Pablo M. Suarez"},"url":"https:\/\/www.seonetdigital.com\/es\/blog\/author\/pablo-suarez"}]}},"_links":{"self":[{"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/posts\/16315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/comments?post=16315"}],"version-history":[{"count":9,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/posts\/16315\/revisions"}],"predecessor-version":[{"id":31440,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/posts\/16315\/revisions\/31440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/media\/22921"}],"wp:attachment":[{"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/media?parent=16315"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/categories?post=16315"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seonetdigital.com\/es\/wp-json\/wp\/v2\/tags?post=16315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}